{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["Sheet1","Sheet2","Sheet3","Sheet4","Sheet5"],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":0,"defined_names":10,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Sheet1","index":0,"n_rows":102,"n_cols":22,"rows_kept":102,"cut":false,"hidden":false,"merged":[[24,1,24,21],[53,5,53,6],[53,7,53,8],[53,9,53,10],[53,11,53,12],[53,19,53,20],[53,13,53,14],[53,15,53,16],[53,17,53,18],[52,5,52,6],[49,17,51,18],[49,19,51,20],[52,7,52,8],[52,9,52,10],[52,11,52,12],[52,13,52,14],[52,15,52,16],[52,17,52,18],[52,19,52,20],[44,7,44,8],[45,7,45,8],[45,5,45,6],[49,13,51,14],[49,15,51,16],[44,13,44,14],[44,15,44,16],[44,17,44,18],[44,19,44,20],[44,11,44,12],[45,11,45,12],[45,19,45,20],[49,5,51,6],[49,7,51,8],[44,9,44,10],[45,9,45,10],[26,1,26,3],[27,1,27,3],[26,4,26,12],[26,13,26,21],[27,4,27,12],[27,13,27,21],[54,18,54,20],[48,1,48,21],[49,1,51,1],[49,2,51,2],[49,3,51,3],[49,4,51,4],[49,21,51,21],[41,21,43,21],[46,18,46,20],[45,15,45,16],[45,17,45,18],[45,13,45,14],[41,19,43,20],[41,17,43,18],[41,15,43,16],[41,13,43,14],[49,9,51,10],[49,11,51,12],[101,20,114,21],[101,2,114,19],[32,1,32,3],[32,4,32,9],[32,10,32,21],[74,1,74,10],[76,1,76,10],[77,1,77,10],[75,1,75,10],[73,3,73,9],[72,1,72,2],[71,1,71,10],[70,4,70,14],[65,16,67,16],[65,17,67,17],[65,18,67,18],[65,19,67,19],[65,20,67,20],[90,1,90,21],[41,11,43,12],[41,9,43,10],[41,7,43,8],[41,5,43,6],[44,5,44,6],[91,1,91,21],[92,1,92,21],[96,1,96,21],[97,1,97,21],[82,6,82,7],[82,8,82,10],[84,1,85,3],[84,4,84,5],[84,6,84,7],[84,8,84,10],[84,11,84,14],[84,15,84,17],[84,18,84,21],[85,4,85,5],[85,6,85,7],[85,8,85,10],[85,11,85,14],[85,15,85,17],[85,18,85,21],[77,12,77,14],[79,1,79,21],[80,1,81,3],[80,4,80,5],[80,6,80,7],[65,21,67,21],[57,13,59,13],[57,14,59,14],[57,15,59,15],[80,8,80,10],[80,11,80,14],[80,15,80,17],[80,18,80,21],[81,4,81,5],[81,6,81,7],[81,8,81,10],[81,11,81,14],[81,15,81,17],[77,18,77,20],[81,18,81,21],[72,18,73,20],[75,18,76,20],[57,2,59,2],[57,3,59,3],[101,1,114,1],[94,1,94,2],[95,1,95,21],[70,18,70,20],[72,3,72,9],[62,18,62,20],[64,1,64,21],[65,1,67,1],[65,2,67,2],[65,3,67,3],[65,4,67,4],[65,5,67,5],[65,6,67,6],[65,7,67,7],[65,8,67,8],[65,9,67,9],[65,10,67,10],[65,11,67,11],[65,12,67,12],[98,1,98,21],[99,1,99,21],[73,12,73,14],[74,12,74,14],[76,12,76,14],[37,1,37,3],[38,1,38,21],[57,16,59,16],[57,17,59,17],[57,18,59,18],[57,19,59,19],[57,21,59,21],[57,5,59,5],[57,6,59,6],[57,7,59,7],[57,11,59,11],[57,12,59,12],[56,1,56,21],[37,4,37,6],[37,7,37,9],[37,10,37,12],[37,13,37,15],[37,16,37,18],[37,19,37,21],[40,1,40,21],[41,1,43,1],[41,2,43,2],[41,3,43,3],[41,4,43,4],[65,13,67,13],[65,14,67,14],[65,15,67,15],[74,18,74,20],[57,8,59,8],[57,9,59,9],[57,10,59,10],[89,1,89,21],[82,11,82,14],[82,15,82,17],[82,18,82,21],[83,4,83,5],[83,6,83,7],[83,8,83,10],[83,15,83,17],[83,18,83,21],[88,1,88,21],[87,1,87,2],[82,1,83,3],[82,4,82,5],[57,1,59,1],[57,4,59,4],[83,11,83,14],[57,20,59,20],[36,4,36,6],[36,7,36,9],[36,10,36,12],[36,13,36,15],[36,16,36,18],[36,19,36,21],[34,7,34,9],[34,10,34,12],[34,13,34,15],[34,16,34,18],[34,19,34,21],[35,4,35,6],[35,7,35,9],[35,10,35,12],[35,13,35,15],[35,16,35,18],[35,19,35,21],[0,4,0,16],[1,4,1,16],[33,16,33,18],[18,4,19,6],[18,7,18,8],[18,9,18,10],[19,7,19,8],[19,9,19,10],[21,9,21,12],[20,7,20,8],[21,7,21,8],[20,4,21,6],[20,18,20,21],[22,4,22,21],[21,18,21,21],[20,16,20,17],[21,16,21,17],[33,10,33,12],[33,13,33,15],[30,1,30,21],[20,1,22,3],[17,1,17,21],[2,4,2,6],[3,4,3,6],[8,14,8,16],[9,1,10,21],[33,1,33,3],[4,4,4,6],[5,4,5,6],[6,4,6,6],[7,4,7,6],[8,4,8,6],[2,7,2,13],[3,7,3,13],[5,7,5,13],[6,7,6,13],[7,7,7,13],[8,7,8,13],[4,7,4,13],[25,1,25,3],[25,4,25,12],[25,13,25,21],[28,1,28,3],[29,1,29,3],[28,4,28,12],[28,13,28,21],[29,4,29,12],[29,13,29,21],[34,1,34,3],[33,4,33,6],[33,7,33,9],[2,14,2,16],[20,13,21,15],[20,9,20,12],[35,1,35,3],[36,1,36,3],[33,19,33,21],[34,4,34,6],[18,1,19,3],[18,11,19,17],[18,18,19,21],[2,17,2,21],[3,17,3,21],[4,17,4,21],[5,17,5,21],[6,17,6,21],[7,17,7,21],[3,14,3,16],[4,14,4,16],[5,14,5,16],[6,14,6,16],[7,14,7,16]]}
[null,null,null,null,"OFITE Viscometer Calibration Report"]
[null,null,null,null,"Oil Calibration Per API Recommended Practices; 13B-1 Annex I.5, 13B-2 Annex J.5, 10B-2 Annex B.3.6 and Specification 13A Section 5.2.6"]
[null,null,null,null,"Order Number:",null,null,304331,null,null,null,null,null,null,"Condition Found:",null,null,"In Calibration"]
[null,null,null,null,"Serial # / Local I.D. #:",null,null,"12-2289",null,null,null,null,null,null,"Condition Left:",null,null,"In Calibration"]
[null,null,null,null,"Calibration Date:",null,null,"2025-12-04",null,null,null,null,null,null,"Repairs Required:",null,null,"Yes"]
[null,null,null,null,"*Recommended Due Date:",null,null,{"$f":"IF(H5=\"\",\"\",H5+365)","v":"2026-12-04"},null,null,null,null,null,null,"As Found Required:",null,null,"Yes (See Report Below)"]
[null,null,null,null,"Certificate Number:",null,null,{"$f":"_xlfn.VALUETOTEXT(H4)&_xlfn.VALUETOTEXT(H5)","v":"12-228945995"},null,null,null,null,null,null,"Bob:",null,null,"B1"]
[null,null,null,null,"Part Number:",null,null,"132-00",null,null,null,null,null,null,"Spring:",null,null,"F1"]
[null,null,null,null,"Model:",null,null,{"$f":"IF(ISNA(VLOOKUP(H8,Sheet4!A:B,2,0)),\"\",VLOOKUP(H8,Sheet4!A:B,2,0))","v":"Hand-Crank Viscometer"}]
[null,"OFI Testing Equipment, Inc. - 11302 Steeplecrest Dr - Houston, Texas - 77065 - Phone: 832.320.7300 - Web: www.ofite.com"]
[]
[]
[]
[]
[]
[]
[]
[null,"TESTING CONDITION AND CALIBRATION FLUIDS INFORMATION"]
[null,"Ambient Conditions",null,null,"Lab / Room Temperature",null,null,"°F",null,"°C",null,"Lab / Room Humidity",null,null,null,null,null,null,47.9]
[null,null,null,null,null,null,null,69.5,null,{"$f":"IF((H20=\"\"),\"\",(H20-32)*5/9)","v":20.833333333333332}]
[null,"Calibration Fluid Activation Date and LOT Number",null,null,{"$f":"Sheet2!G31","v":"100 cP"},null,null,"Activation Date",null,"Calibration Fluid LOT Number",null,null,null,{"$f":"Sheet2!G32","v":"50 cP"},null,null,"Activation Date",null,"Calibration Fluid LOT Number"]
[null,null,null,null,null,null,null,"2025-12-03",null,"3060-08-17",null,null,null,null,null,null,"2025-12-03",null,228501]
[null,null,null,null,"     (Activation Date should not exceed 30 days of the calibration date)    "]
[]
[null,"RPM CHECK"]
[null,"Speed Setting",null,null,300,null,null,null,null,null,null,null,null,600]
[null,"Actual",null,null,299.2,null,null,null,null,null,null,null,null,599.6]
[null,"Allowed Deviation",null,null,6,null,null,null,null,null,null,null,null,12]
[null,"Actual Deviation",null,null,{"$f":"MAX(ABS(E26-E27))","v":0.80000000000001137},null,null,null,null,null,null,null,null,{"$f":"MAX(ABS(N26-N27))","v":0.39999999999997726}]
[null,"Pass / Fail",null,null,{"$f":"IF(OR(E27=\"\"),\"Fail\",IF(E28>=E29,\"Pass\",\"Fail\"))","v":"Pass"},null,null,null,null,null,null,null,null,{"$f":"IF(OR(N27=\"\"),\"Fail\",IF(N28>=N29,\"Pass\",\"Fail\"))","v":"Pass"}]
[null,"There is no specified equipment calibration RPM requirements for a Hand Crank in API / The RPM and deviations mentioned above are OFITE recommendations per the User Manual."]
[]
[null,"RPM CHECK",null,null,"±  1 RPM for speeds <100 RPM",null,null,null,null,null,"±  1 % of nominal speed of 100 RPM or Greater"]
[null,"Speed Setting",null,null,3,null,null,6,null,null,100,null,null,200,null,null,300,null,null,600]
[null,"Actual"]
[null,"Allowed Deviation",null,null,1,null,null,1,null,null,1,null,null,2,null,null,3,null,null,6]
[null,"Actual Deviation",null,null,{"$f":"MAX(ABS(E34-E35))","v":3},null,null,{"$f":"MAX(ABS(H34-H35))","v":6},null,null,{"$f":"MAX(ABS(K34-K35))","v":100},null,null,{"$f":"MAX(ABS(N34-N35))","v":200},null,null,{"$f":"MAX(ABS(Q34-Q35))","v":300},null,null,{"$f":"MAX(ABS(T34-T35))","v":600}]
[null,"Pass / Fail",null,null,{"$f":"IF(OR(E35=\"\"),\"Fail\",IF(E36>=E37,\"Pass\",\"Fail\"))","v":"Fail"},null,null,{"$f":"IF(OR(H35=\"\"),\"Fail\",IF(H36>=H37,\"Pass\",\"Fail\"))","v":"Fail"},null,null,{"$f":"IF(OR(K35=\"\"),\"Fail\",IF(K36>=K37,\"Pass\",\"Fail\"))","v":"Fail"},null,null,{"$f":"IF(OR(N35=\"\"),\"Fail\",IF(N36>=N37,\"Pass\",\"Fail\"))","v":"Fail"},null,null,{"$f":"IF(OR(Q35=\"\"),\"Fail\",IF(Q36>=Q37,\"Pass\",\"Fail\"))","v":"Fail"},null,null,{"$f":"IF(OR(T35=\"\"),\"Fail\",IF(T36>=T37,\"Pass\",\"Fail\"))","v":"Fail"}]
[null,"Per API RP 10B-2 Annex B, Equipment Calibration Requirements"]
[]
[null,"AS FOUND MEASUREMENTS"]
[null,"Calibration Fluid Viscosity","Calibration Fluid LOT Number","Calibration Fluid Temperature","Calibrated Viscosity (CV)","600 RPM Reading",null,{"$f":"Sheet2!L19","v":"600 VIS:  600 Reading  0.5050"},null,"Accepted Deviation",null,"Actual Deviation               (600 VIS - CV)",null,"300 RPM Reading",null,{"$f":"Sheet5!L20","v":"300 VIS:  300  Reading * 1.0000"},null,"Accepted Deviation",null,"Actual Deviation               (300 VIS - CV)",null,"Pass/Fail"]
[]
[]
[null,{"$f":"Sheet5!G31","v":"100 cP"},{"$f":"J22","v":423912},21.4,101.6,195.5,null,{"$f":"IF(Sheet5!$J$15*F45=0,\"\",Sheet5!$J$15*F45)","v":98.735053644000374},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(H45-E45),\"\",H45-E45)","v":-2.8649463559996207},null,98,null,{"$f":"IF(Sheet5!$J$20*Sheet1!N45=0,\"\",Sheet5!$J$20*Sheet1!N45)","v":98},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(P45-E45),\"\",P45-E45)","v":-3.5999999999999943},null,{"$f":"IF(ISERR(IF(AND(ABS(L45)<=Sheet5!$L$16,ABS(T45)<=Sheet5!$L$16),\"Pass\",\"Fail\")),\"\",IF(AND(ABS(L45)<=Sheet5!$L$16,ABS(T45)<=Sheet5!$L$16),\"Pass\",\"Fail\"))","v":"Fail"}]
[null,{"$f":"Sheet5!G32","v":"50 cP"},{"$f":"S22","v":228501},22,51,97.5,null,{"$f":"IF(Sheet5!$J$15*F46=0,\"\",Sheet5!$J$15*F46)","v":49.241267162608878},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(H46-E46),\"\",H46-E46)","v":-1.758732837391122},null,49,null,{"$f":"IF(Sheet5!$J$20*Sheet1!N46=0,\"\",Sheet5!$J$20*Sheet1!N46)","v":49},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(P46-E46),\"\",P46-E46)","v":-2},null,{"$f":"IF(ISERR(IF(AND(ABS(L46)<=Sheet5!$L$16,ABS(T46)<=Sheet5!$L$16),\"Pass\",\"Fail\")),\"\",IF(AND(ABS(L46)<=Sheet5!$L$16,ABS(T46)<=Sheet5!$L$16),\"Pass\",\"Fail\"))","v":"Fail"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"As Found Calibration Results",null,null,{"$f":"IF(OR(V45=\"\",V46=\"\"),\"Fail\",IF(AND(V45 = \"Pass\",V46 = \"Pass\"),\"Pass\",\"Fail\"))","v":"Fail"}]
[]
[null,"AS LEFT MEASUREMENTS"]
[null,"Calibration Fluid Viscosity","Calibration Fluid LOT Number","Calibration Fluid Temperature","Calibrated Viscosity (CV)","600 RPM Reading",null,{"$f":"Sheet2!L19","v":"600 VIS:  600 Reading  0.5050"},null,"Accepted Deviation",null,"Actual Deviation               (600 VIS - CV)",null,"300 RPM Reading",null,{"$f":"Sheet5!L20","v":"300 VIS:  300  Reading * 1.0000"},null,"Accepted Deviation",null,"Actual Deviation               (300 VIS - CV)",null,"Pass/Fail"]
[]
[]
[null,{"$f":"Sheet5!G31","v":"100 cP"},{"$f":"J22","v":423912},21.5,101.4,199.5,null,{"$f":"IF(Sheet5!$J$15*F53=0,\"\",Sheet5!$J$15*F53)","v":100.75520819426124},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(H53-E53),\"\",H53-E53)","v":-0.64479180573876249},null,100.5,null,{"$f":"IF(Sheet5!$J$20*Sheet1!N53=0,\"\",Sheet5!$J$20*Sheet1!N53)","v":100.5},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(P53-E53),\"\",P53-E53)","v":-0.90000000000000568},null,{"$f":"IF(ISERR(IF(AND(ABS(L53)<=Sheet5!$L$16,ABS(T53)<=Sheet5!$L$16),\"Pass\",\"Fail\")),\"\",IF(AND(ABS(L53)<=Sheet5!$L$16,ABS(T53)<=Sheet5!$L$16),\"Pass\",\"Fail\"))","v":"Pass"}]
[null,{"$f":"Sheet5!G32","v":"50 cP"},{"$f":"S22","v":228501},21.2,51.8,102.5,null,{"$f":"IF(Sheet5!$J$15*F54=0,\"\",Sheet5!$J$15*F54)","v":51.766460350434976},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(H54-E54),\"\",H54-E54)","v":-3.3539649565021534E-2},null,52.5,null,{"$f":"IF(Sheet5!$J$20*Sheet1!N54=0,\"\",Sheet5!$J$20*Sheet1!N54)","v":52.5},null,{"$f":"Sheet5!M16","v":"±1.50"},null,{"$f":"IF(ISERR(P54-E54),\"\",P54-E54)","v":0.70000000000000284},null,{"$f":"IF(ISERR(IF(AND(ABS(L54)<=Sheet5!$L$16,ABS(T54)<=Sheet5!$L$16),\"Pass\",\"Fail\")),\"\",IF(AND(ABS(L54)<=Sheet5!$L$16,ABS(T54)<=Sheet5!$L$16),\"Pass\",\"Fail\"))","v":"Pass"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"As Left Calibration Results",null,null,{"$f":"IF(OR(V53=\"\",V54=\"\"),\"Fail\",IF(AND(V53 = \"Pass\",V54 = \"Pass\"),\"Pass\",\"Fail\"))","v":"Pass"}]
[]
[null,"AS FOUND MEASUREMENTS"]
[null,"Calibration Fluid Viscosity","Calibration Fluid LOT Number","Calibration Fluid Temperature","Calibrated Viscosity (CV)","600 RPM Reading",{"$f":"Sheet2!L19","v":"600 VIS:  600 Reading  0.5050"},"Accepted Deviation","Actual Deviation ** (600 VIS - CV)","300 RPM Reading",{"$f":"Sheet2!L20","v":"300 VIS:  300  Reading * 1.0000"},"Accepted Deviation","Actual Deviation (300 VIS - CV)","200 RPM Reading",{"$f":"Sheet2!L21","v":"200 VIS:  200 Reading / 0.6667"},"Accepted Deviation","Actual Deviation (200 VIS - CV)","100 RPM Reading",{"$f":"Sheet2!L22","v":"100 VIS: 100 Reading / 0.3333"},"Accepted Deviation","Actual Deviation (100 VIS - CV)","Pass/Fail"]
[]
[]
[null,{"$f":"Sheet2!G31","v":"100 cP"},{"$f":"J22","v":423912},null,null,null,{"$f":"IF(Sheet2!S7=\"Yes\",IF(Sheet2!$J$15*F61=0,\"\",Sheet2!$J$15*F61),\"-\")","v":""},{"$f":"IF(Sheet2!S7=\"Yes\",Sheet2!M16,\"-\")","v":"±1.50"},{"$f":"IF(Sheet2!S7=\"Yes\",IF(ISERR(G61-E61),\"\",G61-E61),\"-\")","v":""},null,{"$f":"IF(Sheet2!$J$20*Sheet1!J61=0,\"\",Sheet2!$J$20*Sheet1!J61)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(K61-E61),\"\",K61-E61)","v":""},null,{"$f":"IF(Sheet2!$J$16/0.6667*N61=0,\"\",Sheet2!$J$16/0.6667*N61)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(O61-E61),\"\",O61-E61)","v":""},null,{"$f":"IF(R61/Sheet2!$J$22=0,\"\",R61/Sheet2!$J$22)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(S61-E61),\"\",S61-E61)","v":""},{"$f":"Sheet2!S15","v":""}]
[null,{"$f":"Sheet2!G32","v":"50 cP"},{"$f":"S22","v":228501},null,null,null,{"$f":"IF(Sheet2!S7=\"Yes\",IF(Sheet2!$J$15*F62=0,\"\",Sheet2!$J$15*F62),\"-\")","v":""},{"$f":"IF(Sheet2!S7=\"Yes\",Sheet2!M16,\"-\")","v":"±1.50"},{"$f":"IF(Sheet2!S7=\"Yes\",IF(ISERR(G62-E62),\"\",G62-E62),\"-\")","v":""},null,{"$f":"IF(Sheet2!$J$20*Sheet1!J62=0,\"\",Sheet2!$J$20*Sheet1!J62)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(K62-E62),\"\",K62-E62)","v":""},null,{"$f":"IF(Sheet2!$J$16/0.6667*N62=0,\"\",Sheet2!$J$16/0.6667*N62)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(O62-E62),\"\",O62-E62)","v":""},null,{"$f":"IF(R62/Sheet2!$J$22=0,\"\",R62/Sheet2!$J$22)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(S62-E62),\"\",S62-E62)","v":""},{"$f":"Sheet2!U15","v":""}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"As Found Calibration Results",null,null,{"$f":"IF(OR(V61=\"\",V62=\"\"),\"Fail\",IF(AND(V61 = \"Pass\",V62 = \"Pass\"),\"Pass\",\"Fail\"))","v":"Fail"}]
[]
[null,"AS LEFT MEASUREMENTS"]
[null,"Calibration Fluid Viscosity","Calibration Fluid LOT Number","Calibration Fluid Temperature","Calibrated Viscosity (CV)","600 RPM Reading",{"$f":"Sheet2!L19","v":"600 VIS:  600 Reading  0.5050"},"Accepted Deviation","Actual Deviation ** (600 VIS - CV)","300 RPM Reading",{"$f":"Sheet2!L20","v":"300 VIS:  300  Reading * 1.0000"},"Accepted Deviation","Actual Deviation (300 VIS - CV)","200 RPM Reading",{"$f":"Sheet2!L21","v":"200 VIS:  200 Reading / 0.6667"},"Accepted Deviation","Actual Deviation (200 VIS - CV)","100 RPM Reading",{"$f":"Sheet2!L22","v":"100 VIS: 100 Reading / 0.3333"},"Accepted Deviation","Actual Deviation (100 VIS - CV)","Pass/Fail"]
[]
[]
[null,{"$f":"Sheet2!G31","v":"100 cP"},{"$f":"J22","v":423912},null,null,null,{"$f":"IF(Sheet2!S7=\"Yes\",IF(Sheet2!$J$15*F69=0,\"\",Sheet2!$J$15*F69),\"-\")","v":""},{"$f":"IF(Sheet2!S7=\"Yes\",Sheet2!M16,\"-\")","v":"±1.50"},{"$f":"IF(Sheet2!S7=\"Yes\",IF(ISERR(G69-E69),\"\",G69-E69),\"-\")","v":""},null,{"$f":"IF(Sheet2!$J$20*Sheet1!J69=0,\"\",Sheet2!$J$20*Sheet1!J69)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(K69-E69),\"\",K69-E69)","v":""},null,{"$f":"IF(Sheet2!$J$16/0.6667*N69=0,\"\",Sheet2!$J$16/0.6667*N69)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(O69-E69),\"\",O69-E69)","v":""},null,{"$f":"IF(R69/Sheet2!$J$22=0,\"\",R69/Sheet2!$J$22)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(S69-E69),\"\",S69-E69)","v":""},{"$f":"Sheet2!S24","v":""}]
[null,{"$f":"Sheet2!G32","v":"50 cP"},{"$f":"S22","v":228501},null,null,null,{"$f":"IF(Sheet2!S7=\"Yes\",IF(Sheet2!$J$15*F70=0,\"\",Sheet2!$J$15*F70),\"-\")","v":""},{"$f":"IF(Sheet2!S7=\"Yes\",Sheet2!M16,\"-\")","v":"±1.50"},{"$f":"IF(Sheet2!S7=\"Yes\",IF(ISERR(G70-E70),\"\",G70-E70),\"-\")","v":""},null,{"$f":"IF(Sheet2!$J$20*Sheet1!J70=0,\"\",Sheet2!$J$20*Sheet1!J70)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(K70-E70),\"\",K70-E70)","v":""},null,{"$f":"IF(Sheet2!$J$16/0.6667*N70=0,\"\",Sheet2!$J$16/0.6667*N70)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(O70-E70),\"\",O70-E70)","v":""},null,{"$f":"IF(R70/Sheet2!$J$22=0,\"\",R70/Sheet2!$J$22)","v":""},{"$f":"Sheet2!M16","v":"±1.50"},{"$f":"IF(ISERR(S70-E70),\"\",S70-E70)","v":""},{"$f":"Sheet2!U24","v":""}]
[null,null,null,null,"** For viscometers not using a B1F1 configuration, the 600 rpm reading is shown, but is not used for determining a pass/fail.",null,null,null,null,null,null,null,null,null,null,null,null,null,"As Left Calibration Results",null,null,{"$f":"IF(OR(V69=\"\",V70=\"\"),\"Fail\",IF(AND(V69 = \"Pass\",V70 = \"Pass\"),\"Pass\",\"Fail\"))","v":"Fail"}]
[]
[null,"Factory Recommendations*:",null,"Factory recalibration is recommended annually. Uncertainty: 0.5%"]
[null,null,null,"Calibration requirements are determined per customer's Quality Management System.",null,null,null,null,null,null,null,null,"Emad Hanna",null,null,null,{"$f":"CalDate","v":"2025-12-04"}]
[null,null,null,null,null,null,null,null,null,null,null,null,"Calibration Technician",null,null,null,"Date",null,"Technician Signature"]
[null,"Per API RP 13B-1 and -2, viscometers used for testing drilling fluids should be verified with a traceable calibration fluid at least monthly. "]
[null,null,null,null,null,null,null,null,null,null,null,null,"Samantha Korenek",null,null,null,{"$f":"IF(ISBLANK(M77),\"\",TODAY())","v":"2025-12-04"}]
[null,"Per API RP 10B-2, viscometers used for testing cements should be verified for accuracy with a traceable calibration fluid at least quarterly. ",null,null,null,null,null,null,null,null,null,null,"Reviewed By",null,null,null,"Date",null,"Reviewer Signature"]
[]
[null,"CALIBRATION EQUIPMENT"]
[null,"Fluid Thermometer",null,null,709,null,{"$f":"Sheet3!C2","v":"4000-90080-09"},null,{"$f":"Sheet3!B2","v":"240024945"},null,null,{"$f":"Sheet3!F2","v":"4000-14742432"},null,null,null,{"$f":"DATEVALUE(Sheet3!D2)","v":"2024-01-09"},null,null,{"$f":"DATEVALUE(Sheet3!E2)","v":"2026-01-09"}]
[null,null,null,null,"I.D. Number",null,"Model Number",null,"Serial Number",null,null,"Certificate Number",null,null,null,"Calibration Date",null,null,"Calibration Due Date"]
[null,"Tachometer",null,null,155,null,{"$f":"Sheet3!C5","v":"4060"},null,{"$f":"Sheet3!B5","v":"122574032"},null,null,{"$f":"Sheet3!F5","v":"C-52605"},null,null,null,{"$f":"DATEVALUE(Sheet3!D5)","v":"2025-07-23"},null,null,{"$f":"DATEVALUE(Sheet3!E5)","v":"2026-07-23"}]
[null,null,null,null,"I.D. Number",null,"Model Number",null,"Serial Number",null,null,"Certificate Number",null,null,null,"Calibration Date",null,null,"Calibration Due Date"]
[null,"Ambient Monitor / Thermometer",null,null,169,null,{"$f":"Sheet3!C8","v":"EA20"},null,{"$f":"Sheet3!B8","v":"Z375173"},null,null,{"$f":"Sheet3!F8","v":"C-50047"},null,null,null,{"$f":"DATEVALUE(Sheet3!D8)","v":"2025-05-09"},null,null,{"$f":"DATEVALUE(Sheet3!E8)","v":"2026-05-09"}]
[null,null,null,null,"I.D. Number",null,"Model Number",null,"Serial Number",null,null,"Certificate Number",null,null,null,"Calibration Date",null,null,"Calibration Due Date"]
[]
[null,"AS FOUND REPORT"]
[null,"List all damages which were observed. Describe how this could have affected measurements."]
[null,"fail in calibration."]
[]
[]
[]
[]
[null,"AS LEFT REPORT"]
[null,"List all repairs made to the unit under AS LEFT measurements."]
[null,"Replace bearing,shaft housing,shaft cam  and calibrated"]
[]
[]
[]
[]
[null,"Viscometer Calibration Report 12/1/2025","This report meets or exceeds the requirements outlined in API RP 13B-1 Recommended Practice for Field Testing Water-based Drilling Fluids and API RP 13B-2 Recommended Practice for Field Testing Oil-based Drilling Fluids for calibration of laboratory  devices, using certified master test equipment that is traceable to NIST which is a signatory to the Mutual Recognition Arrangement (MRA) with the International Laboratory Accreditation Cooperation (ILAC).",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Page 1 of 1"]

{"sheet":"Sheet2","index":1,"n_rows":62,"n_cols":21,"rows_kept":62,"cut":false,"hidden":true,"merged":[[5,16,5,20],[26,16,26,20]]}
[]
[]
[]
[]
[]
["bob","k2","k3","100*k2/k3",null,null,null,null,null,null,null,null,null,null,null,null,"900 and 800"]
["B1",1.323E-2,1.7022999999999999,{"$f":"100*B7/C7","v":0.77718381013922344},null,null,null,null,null,null,null,null,null,null,null,null,null,"Standard:",{"$f":"IF(AND(Sheet1!R7=\"B1\",Sheet1!R8=\"F1\"),\"Yes\",\"No\")","v":"Yes"}]
["B2",2.6100000000000002E-2,0.377,{"$f":"100*B8/C8","v":6.9230769230769242},null,"100*k2/k3=",{"$f":"VLOOKUP(Sheet1!R7,Sheet2!A6:D11,4,FALSE)","v":0.77718381013922344}]
["B3",5.2900000000000003E-2,0.26800000000000002,{"$f":"100*B9/C9","v":19.738805970149254},null,"k1=",{"$f":"VLOOKUP(Sheet1!R8,Sheet2!A14:B21,2,FALSE)","v":386},null,null,null,null,null,null,null,null,null,"as found"]
["B4",0.106,0.26800000000000002,{"$f":"100*B10/C10","v":39.552238805970148},null,null,null,null,null,null,null,null,null,null,null,null,null,"Fluid 1","Pass/Fail","Fluid 2","Pass/Faill"]
["B5",1.54E-2,0.85029999999999994,{"$f":"100*B11/C11","v":1.8111254851228979},null,null,null,null,null,null,null,null,null,null,null,null,"600 rpm",{"$f":"Sheet1!I61","v":""},{"$f":"IF(R11=\"\",\"\",IF(S7=\"Yes\",IF(ISERR(IF(ABS(R11)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R11)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":""},{"$f":"Sheet1!I62","v":""},{"$f":"IF(T11=\"\",\"\",IF(S7=\"Yes\",IF(ISERR(IF(ABS(T11)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(T11)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":""}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"300 rpm",{"$f":"Sheet1!M61","v":""},{"$f":"IF(ISERR(IF(ABS(R12)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R12)<=$L$16,\"Pass\",\"Fail\"))","v":""},{"$f":"Sheet1!M62","v":""},""]
["Spring","k1",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"200 rpm",{"$f":"Sheet1!Q61","v":""},"",{"$f":"Sheet1!Q62","v":""},""]
["F0.2",77.2,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"100 rpm",{"$f":"Sheet1!U61","v":""},"",{"$f":"Sheet1!U62","v":""},""]
["F0.5",193,null,null,null,null,{"$f":"G8*G9/600","v":0.49998825118956708},null,null,{"$f":"G15*2/1.98","v":0.50503863756521927},null,null,null,null,null,null,null,null,{"$f":"IF(COUNTIF(S11:S14,\"Pass\")=4,\"Pass\",IF(COUNTIF(S11:S14,\"Fail\")>0,\"Fail\",\"\"))","v":""},null,{"$f":"IF(COUNTIF(U11:U14,\"Pass\")=4,\"Pass\",IF(COUNTIF(U11:U14,\"Fail\")>0,\"Fail\",\"\"))","v":""}]
["F1",386,null,null,null,null,{"$f":"G8*G9/300","v":0.99997650237913416},null,null,{"$f":"G16","v":0.99997650237913416},null,{"$f":"ROUND((1.5*G16),2)","v":1.5},{"$f":"\"±\"&TEXT((1.5*G16),\"#.00\")","v":"±1.50"}]
["F2",772,null,null,null,null,{"$f":"1/(G8*G9/200)","v":0.66668233211534467},null,null,{"$f":"G17","v":0.66668233211534467}]
["F3",1158,null,null,null,null,{"$f":"1/(G8*G9/100)","v":0.33334116605767233},null,null,{"$f":"G18","v":0.33334116605767233},null,null,null,null,null,null,"as left"]
["F4",1544,null,null,null,null,null,null,null,{"$f":"FIXED(J15,4)","v":"0.5050"},null,{"$f":"\"600 VIS:  600 Reading  \"&J19","v":"600 VIS:  600 Reading  0.5050"},null,null,null,null,null,"Fluid 1","Pass/Fail","Fluid 2","Pass/Faill"]
["F5",1930,null,null,null,null,2.3303147908581288,null,null,{"$f":"FIXED(J16,4)","v":"1.0000"},null,{"$f":"\"300 VIS:  300  Reading * \"&J20","v":"300 VIS:  300  Reading * 1.0000"},null,null,null,null,"600 rpm",{"$f":"Sheet1!I69","v":""},{"$f":"IF(R20=\"\",\"\",IF(S16=\"Yes\",IF(ISERR(IF(ABS(R20)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R20)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":""},{"$f":"Sheet1!I70","v":""},{"$f":"IF(T20=\"\",\"\",IF(S16=\"Yes\",IF(ISERR(IF(ABS(T20)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(T20)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":""}]
["F10",3860,null,null,null,null,null,null,null,{"$f":"FIXED(J17,4)","v":"0.6667"},null,{"$f":"\"200 VIS:  200 Reading / \"&J21","v":"200 VIS:  200 Reading / 0.6667"},null,null,null,null,"300 rpm",{"$f":"Sheet1!M69","v":""},{"$f":"IF(ISERR(IF(ABS(R21)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R21)<=$L$16,\"Pass\",\"Fail\"))","v":""},{"$f":"Sheet1!M70","v":""},{"$f":"IF(ISERR(IF(ABS(T21)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(T21)<=$L$16,\"Pass\",\"Fail\"))","v":""}]
[null,null,null,null,null,null,null,null,null,{"$f":"FIXED(J18,4)","v":"0.3333"},null,{"$f":"\"100 VIS: 100 Reading / \"&J22","v":"100 VIS: 100 Reading / 0.3333"},null,null,null,null,"200 rpm",{"$f":"Sheet1!Q69","v":""},"",{"$f":"Sheet1!Q70","v":""},""]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"100 rpm",{"$f":"Sheet1!U69","v":""},"",{"$f":"Sheet1!U70","v":""},""]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(COUNTIF(S20:S23,\"Pass\")=4,\"Pass\",IF(COUNTIF(S20:S23,\"Fail\")>0,\"Fail\",\"\"))","v":""},null,{"$f":"IF(COUNTIF(U20:U23,\"Pass\")=4,\"Pass\",IF(COUNTIF(U20:U23,\"Fail\")>0,\"Fail\",\"\"))","v":""}]
[]
[null,null,null,null,null,"1000 cP","500 cP","200 cP","100 cP","50 cP","20 cP"]
[null,null,null,null,null,"500 cP","200 cP","100 cP","50 cP","20 cP","10 cP"]
[]
[]
[]
[null,null,null,null,null,null,{"$f":"IF(J16>7,F26,IF(J16>3.5,G26,IF(J16>1.4,H26,IF(J16>0.7,I26,IF(J16>0.35,J26,K26)))))","v":"100 cP"}]
[null,null,null,null,null,null,{"$f":"IF(J16>7,F27,IF(J16>3.5,G27,IF(J16>1.4,H27,IF(J16>0.7,I27,IF(J16>0.35,J27,K27)))))","v":"50 cP"}]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(COUNTIF(S32:S35,\"Pass\")=4,\"Pass\",IF(COUNTIF(S32:S35,\"Fail\")>0,\"Fail\",\"\"))","v":""},null,{"$f":"IF(COUNTIF(U32:U35,\"Pass\")=4,\"Pass\",IF(COUNTIF(U32:U35,\"Fail\")>0,\"Fail\",\"\"))","v":""}]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"as left"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fluid 1","Pass/Fail","Fluid 2","Pass/Faill"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"600 rpm",{"$f":"Sheet1!L53","v":-0.64479180573876249},{"$f":"IF(R41=\"\",\"\",IF(S37=\"Yes\",IF(ISERR(IF(ABS(R41)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R41)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":"Pass"},{"$f":"Sheet1!L54","v":-3.3539649565021534E-2},{"$f":"IF(T41=\"\",\"\",IF(S37=\"Yes\",IF(ISERR(IF(ABS(T41)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(T41)<=$L$16,\"Pass\",\"Fail\")),\"Pass\"))","v":"Pass"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"300 rpm",{"$f":"Sheet1!T53","v":-0.90000000000000568},{"$f":"IF(ISERR(IF(ABS(R42)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(R42)<=$L$16,\"Pass\",\"Fail\"))","v":"Pass"},{"$f":"Sheet1!T54","v":0.70000000000000284},{"$f":"IF(ISERR(IF(ABS(T42)<=$L$16,\"Pass\",\"Fail\")),\"\",IF(ABS(T42)<=$L$16,\"Pass\",\"Fail\"))","v":"Pass"}]
["OFI Testing Equipment"]
[]
[]
[]
[]
["New"]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
[]
[]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
["F°"]
["C°"]

{"sheet":"Sheet3","index":2,"n_rows":62,"n_cols":6,"rows_kept":62,"cut":false,"hidden":true,"merged":[]}
["AliasID","SerialNumber","Model","CalDate","DueDate","CalibrationNumber"]
[709,"240024945","4000-90080-09","2024-01-09","2026-01-09","4000-14742432"]
[]
["AliasID","SerialNumber","Model","CalDate","DueDate","CalibrationNumber"]
[155,"122574032","4060","2025-07-23","2026-07-23","C-52605"]
[]
["AliasID","SerialNumber","Model","CalDate","DueDate","CalibrationNumber"]
[169,"Z375173","EA20","2025-05-09","2026-05-09","C-50047"]
[]
[]
[]
[]
["130-00-C"]
["130-00-C-H"]
["130-00-1-C-H"]
["130-00-C-T"]
["130-00-1-C-T"]
["130-10"]
["130-10-B"]
["130-10-S"]
["130-10-C"]
["130-10-C-S"]
["130-10-C-H"]
["130-10-L"]
["130-10-L-S"]
["130-10-99"]
["130-11-C"]
["130-60"]
["130-60-99"]
["130-60-12"]
["130-70-12"]
["130-70-99"]
["130-76"]
["130-76-C"]
["130-76-1-C"]
["130-76-H-C"]
["130-76-1-H-C"]
["130-76-K"]
["130-76-1-K-C"]
["130-76-LSK"]
["130-76-99"]
["130-76-600"]
["132-00"]
["132-00-99"]
["900-02807"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["F°"]
["C°"]

{"sheet":"Sheet4","index":3,"n_rows":62,"n_cols":14,"rows_kept":62,"cut":false,"hidden":true,"merged":[]}
["130-00-C","Model 800E Viscometer 115V / 230V"]
["130-00-C-H","Model 800E Viscometer 115V w/ Heat Cup"]
["130-00-1-C-H","Model 800E Viscometer 230V w/ Heat Cup"]
["130-00-C-T","Model 800E Viscometer 115V w/ Tablet"]
["130-00-1-C-T","Model 800E Viscometer 230V w/ Tablet"]
["130-10","Model 800 Viscometer"]
["130-10-C","Model 800 Viscometer, Complete"]
["130-10-C-H","Model 800 Viscometer, Hastelloy"]
["130-10-L","Model 800 Viscometer with Retractable Legs"]
["130-10-99","Model 800 Viscometer, Reconditioned"]
["130-60","6-Speed Viscometer"]
["130-60-99","6-Speed Viscometer, Reconditioned",null,"rpm","b1 100","b1 200","b5 100","b5 200"]
["130-76","Model 900 Viscometer",null,50,17.2,34.5,7.5,15.5]
["130-76-C","Model 900 Viscometer, Complete, 115 Volt",null,100,34.200000000000003,69.099999999999994,15,31]
["130-76-1-C","Model 900 Viscometer, Complete, 230 Volt",null,150,51.3,103.9,22.4,46.5]
["130-76-H-C","Model 900 Viscometer, Hastelloy, 115 Volt",null,200,68.099999999999994,138.19999999999999,29.8,61.9]
["130-76-1-H-C","Model 900 Viscometer, Hastelloy, 230 Volt",null,250,85.1,172.4,37.200000000000003,77.2,null,null,"rpm","b1 100","b5 100","b5 200"]
["130-76-K","Model 900 Viscometer with KlikLok Bob, 115 Volt",null,300,101.9,206.5,44.6,92.5,null,null,300,101.9,44.6,92.5]
["130-76-1-K-C","Model 900 Viscometer with KlikLok Bob, 230 Volt",null,350,118.5,240.6,51.7,107.8,null,null,350,118.5,51.7,107.8]
["130-76-LSK","Model 900 LS Conversion Kit",null,400,134.80000000000001,274.10000000000002,58.9,122.4,null,null,400,134.80000000000001,58.9,122.4]
["130-76-99","Model 900 Viscometer (Reconditioned)",null,450,151.30000000000001,305.5,66.099999999999994,136.9,null,null,450,151.30000000000001,66.099999999999994,136.9]
["130-76-600","Model 900 Viscometer with No Legs or Base",null,500,167.8,337.8,73.2,151.5,null,null,500,167.8,73.2,151.5]
["Other","Other",null,550,184.1,341.8,80.2,165.8,null,null,550,184.1,80.2,165.8]
["130-60-12","12 Speed Viscometer, 60 Hz",null,600,200.1,341.8,87.3,180.1,null,null,600,200.1,87.3,180.1]
["130-70-12","12 Speed Viscometer, 50 Hz"]
["900-02807","Model 900 Viscometer less Heat Cup"]
["130-10-C-S","Model 800 Viscometer , Complete, Stability Motor"]
["130-10-S","Model 800 Viscometer, Stability Motor"]
["130-10-L-S","Model 800 Viscometer,Retractable Legs,Stability Motor"]
["130-10-B","Model 800, Brookfield Model"]
["130-11-C","Model 800 Viscometer , Complete, Stability Motor"]
["132-00","Hand-Crank Viscometer"]
["132-00-99","Hand-Crank Viscometer, Reconditioned"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["OFI Testing Equipment"]
[]
[]
[]
[]
["New"]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
[]
[]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
["F°"]
["C°"]

{"sheet":"Sheet5","index":4,"n_rows":62,"n_cols":13,"rows_kept":62,"cut":false,"hidden":true,"merged":[[5,16,5,20],[26,16,26,20]]}
[]
[]
[]
[]
[]
["bob","k2","k3","100*k2/k3"]
["B1",1.323E-2,1.7022999999999999,{"$f":"100*B7/C7","v":0.77718381013922344}]
["B2",2.6100000000000002E-2,0.377,{"$f":"100*B8/C8","v":6.9230769230769242},null,"100*k2/k3=",{"$f":"VLOOKUP(Sheet1!R7,Sheet5!A6:D11,4,FALSE)","v":0.77718381013922344}]
["B3",5.2900000000000003E-2,0.26800000000000002,{"$f":"100*B9/C9","v":19.738805970149254},null,"k1=",{"$f":"VLOOKUP(Sheet1!R8,Sheet5!A14:B21,2,FALSE)","v":386}]
["B4",0.106,0.26800000000000002,{"$f":"100*B10/C10","v":39.552238805970148}]
["B5",1.54E-2,0.85029999999999994,{"$f":"100*B11/C11","v":1.8111254851228979}]
[]
["Spring","k1"]
["F0.2",77.2]
["F0.5",193,null,null,null,null,{"$f":"G8*G9/600","v":0.49998825118956708},null,null,{"$f":"G15*2/1.98","v":0.50503863756521927}]
["F1",386,null,null,null,null,{"$f":"G8*G9/300","v":0.99997650237913416},null,null,{"$f":"G16","v":0.99997650237913416},null,{"$f":"ROUND((1.5*G16),2)","v":1.5},{"$f":"\"±\"&TEXT((1.5*G16),\"#.00\")","v":"±1.50"}]
["F2",772,null,null,null,null,{"$f":"1/(G8*G9/200)","v":0.66668233211534467},null,null,{"$f":"G17","v":0.66668233211534467}]
["F3",1158,null,null,null,null,{"$f":"1/(G8*G9/100)","v":0.33334116605767233},null,null,{"$f":"G18","v":0.33334116605767233}]
["F4",1544,null,null,null,null,null,null,null,{"$f":"FIXED(J15,4)","v":"0.5050"},null,{"$f":"\"600 VIS:  600 Reading * \"&J19","v":"600 VIS:  600 Reading * 0.5050"}]
["F5",1930,null,null,null,null,2.3303147908581288,null,null,{"$f":"FIXED(J16,4)","v":"1.0000"},null,{"$f":"\"300 VIS:  300  Reading * \"&J20","v":"300 VIS:  300  Reading * 1.0000"}]
["F10",3860,null,null,null,null,null,null,null,{"$f":"FIXED(J17,4)","v":"0.6667"},null,{"$f":"\"200 VIS:  200 Reading / \"&J21","v":"200 VIS:  200 Reading / 0.6667"}]
[null,null,null,null,null,null,null,null,null,{"$f":"FIXED(J18,4)","v":"0.3333"},null,{"$f":"\"100 VIS: 100 Reading / \"&J22","v":"100 VIS: 100 Reading / 0.3333"}]
[]
[]
[]
[null,null,null,null,null,"1000 cP","500 cP","200 cP","100 cP","50 cP","20 cP"]
[null,null,null,null,null,"500 cP","200 cP","100 cP","50 cP","20 cP","10 cP"]
[]
[]
[]
[null,null,null,null,null,null,{"$f":"IF(J16>7,F26,IF(J16>3.5,G26,IF(J16>1.4,H26,IF(J16>0.7,I26,IF(J16>0.35,J26,K26)))))","v":"100 cP"}]
[null,null,null,null,null,null,{"$f":"IF(J16>7,F27,IF(J16>3.5,G27,IF(J16>1.4,H27,IF(J16>0.7,I27,IF(J16>0.35,J27,K27)))))","v":"50 cP"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["OFI Testing Equipment"]
[]
[]
[]
[]
["New"]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
[]
[]
["In Calibration"]
["Out of Calibration"]
[]
[]
[]
["F°"]
["C°"]